{"id":45,"count":6,"description":"","link":"https:\/\/coverclass.com.br\/es\/product-category\/pacotes\/","name":"Pacotes","slug":"pacotes","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/coverclass.com.br\/es\/wp-json\/wp\/v2\/product_cat\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coverclass.com.br\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/coverclass.com.br\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/coverclass.com.br\/es\/wp-json\/wp\/v2\/product?product_cat=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}